{"id":426,"count":1,"description":"","link":"http:\/\/sites.coloradocollege.edu\/atb\/tag\/steve-crosby\/","name":"Steve Crosby","slug":"steve-crosby","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/sites.coloradocollege.edu\/atb\/wp-json\/wp\/v2\/tags\/426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sites.coloradocollege.edu\/atb\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/sites.coloradocollege.edu\/atb\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/sites.coloradocollege.edu\/atb\/wp-json\/wp\/v2\/posts?tags=426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}